{"id":40,"date":"2025-11-03T09:58:02","date_gmt":"2025-11-03T09:58:02","guid":{"rendered":"https:\/\/wp.ravextheme.com\/archidex\/?page_id=40"},"modified":"2026-03-24T10:47:44","modified_gmt":"2026-03-24T10:47:44","slug":"interaction-02","status":"publish","type":"page","link":"https:\/\/remark3demos3.com\/Terrano\/interaction-02\/","title":{"rendered":"Interaction 02"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"40\" class=\"elementor elementor-40\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f63904 e-con-full e-flex e-con e-parent\" data-id=\"1f63904\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a9943 elementor-widget elementor-widget-archidex_hero_slider\" data-id=\"d2a9943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"archidex_hero_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n            \r\n                <section class=\"interactive-Project\">\r\n                    <div class=\"interactive-Project__wrapper\">\r\n                        <div class=\"interactive-Project__wrap\">\r\n                            <div class=\"interactive-Project__content\">\r\n                                                                <div class=\"interactive-Project__item active\" data-image=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-34.jpg\">\r\n                                    <div class=\"interactive-Project__text-box\">\r\n                                                                                    <span class=\"number\">\r\n                                                001                                            <\/span>\r\n                                                                                                                            <h4 class=\"title\">\r\n                                                <a href=\"https:\/\/remark3demos3.com\/Terrano\/portfolio-details\/\" target=\"_self\" rel=\"nofollow\">\r\n                                                    RESIDENT DUBAI                                                <\/a>\r\n                                            <\/h4>\r\n                                                                            <\/div>\r\n                                    <div class=\"icon\">\r\n                                        <span><i class=\"fa fa-light fa-arrow-right\"><\/i><\/span>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"interactive-Project__item active\" data-image=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-33.jpg\">\r\n                                    <div class=\"interactive-Project__text-box\">\r\n                                                                                    <span class=\"number\">\r\n                                                002                                            <\/span>\r\n                                                                                                                            <h4 class=\"title\">\r\n                                                <a href=\"https:\/\/remark3demos3.com\/Terrano\/portfolio-details\/\" target=\"_self\" rel=\"nofollow\">\r\n                                                    RESIDENT DUBAI                                                <\/a>\r\n                                            <\/h4>\r\n                                                                            <\/div>\r\n                                    <div class=\"icon\">\r\n                                        <span><i class=\"fa fa-light fa-arrow-right\"><\/i><\/span>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"interactive-Project__item active\" data-image=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-35.jpg\">\r\n                                    <div class=\"interactive-Project__text-box\">\r\n                                                                                    <span class=\"number\">\r\n                                                003                                            <\/span>\r\n                                                                                                                            <h4 class=\"title\">\r\n                                                <a href=\"https:\/\/remark3demos3.com\/Terrano\/portfolio-details\/\" target=\"_self\" rel=\"nofollow\">\r\n                                                    PROJECT NO:32                                                <\/a>\r\n                                            <\/h4>\r\n                                                                            <\/div>\r\n                                    <div class=\"icon\">\r\n                                        <span><i class=\"fa fa-light fa-arrow-right\"><\/i><\/span>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"interactive-Project__item active\" data-image=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-36.jpg\">\r\n                                    <div class=\"interactive-Project__text-box\">\r\n                                                                                    <span class=\"number\">\r\n                                                004                                            <\/span>\r\n                                                                                                                            <h4 class=\"title\">\r\n                                                <a href=\"https:\/\/remark3demos3.com\/Terrano\/portfolio-details\/\" target=\"_self\" rel=\"nofollow\">\r\n                                                    MODERN HOUSE                                                <\/a>\r\n                                            <\/h4>\r\n                                                                            <\/div>\r\n                                    <div class=\"icon\">\r\n                                        <span><i class=\"fa fa-light fa-arrow-right\"><\/i><\/span>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"interactive-Project__item active\" data-image=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-37.jpg\">\r\n                                    <div class=\"interactive-Project__text-box\">\r\n                                                                                    <span class=\"number\">\r\n                                                005                                            <\/span>\r\n                                                                                                                            <h4 class=\"title\">\r\n                                                <a href=\"https:\/\/remark3demos3.com\/Terrano\/portfolio-details\/\" target=\"_self\" rel=\"nofollow\">\r\n                                                    LUX MODERN VILA                                                <\/a>\r\n                                            <\/h4>\r\n                                                                            <\/div>\r\n                                    <div class=\"icon\">\r\n                                        <span><i class=\"fa fa-light fa-arrow-right\"><\/i><\/span>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"interactive-Project__item active\" data-image=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-38.jpg\">\r\n                                    <div class=\"interactive-Project__text-box\">\r\n                                                                                    <span class=\"number\">\r\n                                                006                                            <\/span>\r\n                                                                                                                            <h4 class=\"title\">\r\n                                                <a href=\"https:\/\/remark3demos3.com\/Terrano\/portfolio-details\/\" target=\"_self\" rel=\"nofollow\">\r\n                                                    AMY MINIMAL CENTRE                                                <\/a>\r\n                                            <\/h4>\r\n                                                                            <\/div>\r\n                                    <div class=\"icon\">\r\n                                        <span><i class=\"fa fa-light fa-arrow-right\"><\/i><\/span>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                <div class=\"interactive-Project__item active\" data-image=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-39.jpg\">\r\n                                    <div class=\"interactive-Project__text-box\">\r\n                                                                                    <span class=\"number\">\r\n                                                007                                            <\/span>\r\n                                                                                                                            <h4 class=\"title\">\r\n                                                <a href=\"https:\/\/remark3demos3.com\/Terrano\/portfolio-details\/\" target=\"_self\" rel=\"nofollow\">\r\n                                                    AMY MINIMAL CENTRE                                                <\/a>\r\n                                            <\/h4>\r\n                                                                            <\/div>\r\n                                    <div class=\"icon\">\r\n                                        <span><i class=\"fa fa-light fa-arrow-right\"><\/i><\/span>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                            <\/div>\r\n                            <div class=\"interactive-Project__thumb\">\r\n                                                                                                    <img decoding=\"async\" class=\"active\" src=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-34.jpg\" alt=\"\">\r\n                                                                                                                                    <img decoding=\"async\" class=\"active\" src=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-33.jpg\" alt=\"\">\r\n                                                                                                                                    <img decoding=\"async\" class=\"active\" src=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-35.jpg\" alt=\"\">\r\n                                                                                                                                    <img decoding=\"async\" class=\"active\" src=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-36.jpg\" alt=\"\">\r\n                                                                                                                                    <img decoding=\"async\" class=\"active\" src=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-37.jpg\" alt=\"\">\r\n                                                                                                                                    <img decoding=\"async\" class=\"active\" src=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-38.jpg\" alt=\"\">\r\n                                                                                                                                    <img decoding=\"async\" class=\"active\" src=\"https:\/\/remark3demos3.com\/Terrano\/wp-content\/uploads\/2025\/11\/project-39.jpg\" alt=\"\">\r\n                                                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n\r\n            \r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>001 RESIDENT DUBAI 002 RESIDENT DUBAI 003 PROJECT NO:32 004 MODERN HOUSE 005 LUX MODERN VILA 006 AMY MINIMAL CENTRE 007 AMY MINIMAL CENTRE<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-40","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/pages\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":1,"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/pages\/40\/revisions"}],"predecessor-version":[{"id":4317,"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/pages\/40\/revisions\/4317"}],"wp:attachment":[{"href":"https:\/\/remark3demos3.com\/Terrano\/wp-json\/wp\/v2\/media?parent=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}